{"id":251621,"date":"2024-06-12T05:02:50","date_gmt":"2024-06-12T03:02:50","guid":{"rendered":"https:\/\/mueller-trade.com\/shop\/unkategorisiert\/veste-de-cuisiniere-femme-manches-longues\/"},"modified":"2025-09-01T10:53:05","modified_gmt":"2025-09-01T08:53:05","slug":"veste-de-cuisiniere-femme-manches-longues","status":"publish","type":"product","link":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/","title":{"rendered":"Veste de cuisini\u00e8re femme manches longues"},"content":{"rendered":"<\/p>\n<ul>\n<li>\n<ul>\n<li>forme l\u00e9g\u00e8rement cintr\u00e9e, moderne<\/li>\n<li>\u00e9lastique<\/li>\n<li>trous d\u2019a\u00e9ration<\/li>\n<li>poche sur le bras<\/li>\n<li>Poches appliqu\u00e9es \u00e0 rabat dans le dos<\/li>\n<\/ul>\n<p>Tailles\u00a0:\u00a0XS &#8211; 2XL<\/p>\n<p>49% coton, 49% polyester, 2% elastolefin<\/p>\n<p class=\"care-icons\">e 9<span style=\"font-size: 1.143em\">\u00a01 n_W<\/span><\/p>\n<p class=\"care-icons\">\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Text all<\/p>\n<p> [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/\">plus<span class=\"screen-reader-text\"> from Veste de cuisini\u00e8re femme manches longues<\/span><\/a><\/p>\n","protected":false},"featured_media":51744,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"pwb-brand":[4547],"product_cat":[1262,3365,3460,3489,3487],"product_tag":[],"class_list":{"0":"post-251621","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-greiff-fr","7":"product_cat-tout","8":"product_cat-vetements-de-cuisine","9":"product_cat-service-cuisine-fr","10":"product_cat-vestes-cuisine-sk-fr","11":"product_cat-vetements-cuisine-sk-fr","12":"pa_color-010-noir","13":"pa_color-090-blanc","14":"pa_color-group-blanc","15":"pa_color-group-noir","16":"pa_fit-regular-fit","17":"pa_gender-femmes","18":"pa_size-international-xs-fr","19":"pa_size-international-s-fr","20":"pa_size-international-m-fr","21":"pa_size-international-l-fr","22":"pa_size-international-xl-fr","23":"pa_size-international-xxl-fr","25":"first","26":"instock","27":"taxable","28":"shipping-taxable","29":"purchasable","30":"product-type-variable"},"yoast_head":"<title>Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade<\/title>\n<meta name=\"description\" content=\"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade\" \/>\n<meta property=\"og:description\" content=\"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00fcller Trade\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-01T08:53:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/\",\"url\":\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/\",\"name\":\"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade\",\"isPartOf\":{\"@id\":\"https:\/\/mueller-trade.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/5407_6220_010_V.jpg\",\"datePublished\":\"2024-06-12T03:02:50+00:00\",\"dateModified\":\"2025-09-01T08:53:05+00:00\",\"description\":\"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade\",\"breadcrumb\":{\"@id\":\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#primaryimage\",\"url\":\"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/5407_6220_010_V.jpg\",\"contentUrl\":\"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/5407_6220_010_V.jpg\",\"width\":1009,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/mueller-trade.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/mueller-trade.com\/fr\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Veste de cuisini\u00e8re femme manches longues\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mueller-trade.com\/fr\/#website\",\"url\":\"https:\/\/mueller-trade.com\/fr\/\",\"name\":\"M\u00fcller Trade\",\"description\":\"VOTRE BOUTIQUE B2B DE V\u00caTEMENTS PROFESSIONNELS\",\"publisher\":{\"@id\":\"https:\/\/mueller-trade.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mueller-trade.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mueller-trade.com\/fr\/#organization\",\"name\":\"M\u00fcller Trade Corporate Clothing\",\"url\":\"https:\/\/mueller-trade.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mueller-trade.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/cropped-cropped-mt-icon.png\",\"contentUrl\":\"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/cropped-cropped-mt-icon.png\",\"width\":512,\"height\":512,\"caption\":\"M\u00fcller Trade Corporate Clothing\"},\"image\":{\"@id\":\"https:\/\/mueller-trade.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade","description":"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/","og_locale":"fr_FR","og_type":"article","og_title":"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade","og_description":"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade","og_url":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/","og_site_name":"M\u00fcller Trade","article_modified_time":"2025-09-01T08:53:05+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/","url":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/","name":"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade","isPartOf":{"@id":"https:\/\/mueller-trade.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#primaryimage"},"image":{"@id":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#primaryimage"},"thumbnailUrl":"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/5407_6220_010_V.jpg","datePublished":"2024-06-12T03:02:50+00:00","dateModified":"2025-09-01T08:53:05+00:00","description":"Veste de cuisini\u00e8re femme manches longues - M\u00fcller Trade","breadcrumb":{"@id":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#primaryimage","url":"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/5407_6220_010_V.jpg","contentUrl":"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/5407_6220_010_V.jpg","width":1009,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/mueller-trade.com\/fr\/shop\/service-cuisine-fr\/vetements-cuisine-sk-fr\/vestes-cuisine-sk-fr\/veste-de-cuisiniere-femme-manches-longues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mueller-trade.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mueller-trade.com\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Veste de cuisini\u00e8re femme manches longues"}]},{"@type":"WebSite","@id":"https:\/\/mueller-trade.com\/fr\/#website","url":"https:\/\/mueller-trade.com\/fr\/","name":"M\u00fcller Trade","description":"VOTRE BOUTIQUE B2B DE V\u00caTEMENTS PROFESSIONNELS","publisher":{"@id":"https:\/\/mueller-trade.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mueller-trade.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mueller-trade.com\/fr\/#organization","name":"M\u00fcller Trade Corporate Clothing","url":"https:\/\/mueller-trade.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mueller-trade.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/cropped-cropped-mt-icon.png","contentUrl":"https:\/\/mueller-trade.com\/wp-content\/uploads\/sites\/2\/cropped-cropped-mt-icon.png","width":512,"height":512,"caption":"M\u00fcller Trade Corporate Clothing"},"image":{"@id":"https:\/\/mueller-trade.com\/fr\/#\/schema\/logo\/image\/"}}]}},"acf":[],"brands":[{"id":4547,"name":"Greiff","slug":"greiff-fr"}],"_links":{"self":[{"href":"https:\/\/mueller-trade.com\/fr\/wp-json\/wp\/v2\/product\/251621"}],"collection":[{"href":"https:\/\/mueller-trade.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mueller-trade.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mueller-trade.com\/fr\/wp-json\/wp\/v2\/media\/51744"}],"wp:attachment":[{"href":"https:\/\/mueller-trade.com\/fr\/wp-json\/wp\/v2\/media?parent=251621"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/mueller-trade.com\/fr\/wp-json\/wp\/v2\/pwb-brand?post=251621"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mueller-trade.com\/fr\/wp-json\/wp\/v2\/product_cat?post=251621"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mueller-trade.com\/fr\/wp-json\/wp\/v2\/product_tag?post=251621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}